{"id":803,"date":"2020-11-11T17:55:12","date_gmt":"2020-11-11T20:55:12","guid":{"rendered":"https:\/\/www.setasistemas.com.br\/blog\/?p=803"},"modified":"2022-11-06T15:10:29","modified_gmt":"2022-11-06T18:10:29","slug":"prefeitura-de-goiania-autoriza-retomada-das-aulas-presenciais","status":"publish","type":"post","link":"https:\/\/www.setasistemas.com.br\/blog\/2020\/11\/11\/prefeitura-de-goiania-autoriza-retomada-das-aulas-presenciais\/","title":{"rendered":"Prefeitura de Goi\u00e2nia autoriza retomada das aulas presenciais"},"content":{"rendered":"\n<p>Decreto assinado pelo prefeito Iris Rezende e publicado no Di\u00e1rio Oficial do Munic\u00edpio nesta quarta-feira (11\/11) autorizou a retomada das aulas presenciais em todos os n\u00edveis das institui\u00e7\u00f5es de ensino p\u00fablicas e privadas em Goi\u00e2nia. As aulas presenciais estavam suspensas na capital desde mar\u00e7o \u00faltimo, quando a cidade foi alcan\u00e7ada pela pandemia do novo coronav\u00edrus.<\/p>\n\n\n\n<p>De acordo com o decreto, as medidas adotadas pelas autoridades, como a ado\u00e7\u00e3o de protocolos sanit\u00e1rios bastante r\u00edgidos para o exerc\u00edcio das atividades econ\u00f4micas na capital, e o fato de que as a\u00e7\u00f5es de restri\u00e7\u00e3o de funcionamento dessas atividades representam uma decis\u00e3o pol\u00edtica multidimensional, envolvendo o equil\u00edbrio entre os benef\u00edcios da sa\u00fade p\u00fablica com outros impactos sociais e econ\u00f4micos, a autoriza\u00e7\u00e3o para a volta das aulas presenciais \u00e9 uma medida tempestiva, tomada de acordo com as condi\u00e7\u00f5es epidemiol\u00f3gicas favor\u00e1veis atestadas pelos \u00f3rg\u00e3os competentes.<\/p>\n\n\n\n<p>O expediente legal desta quarta-feira lembra que o Centro de Opera\u00e7\u00f5es de Emerg\u00eancia em Sa\u00fade P\u00fablica para o novo Coronav\u00edrus no munic\u00edpio de Goi\u00e2nia (COE Municipal) realizou reuni\u00e3o no dia 3 de novembro, em que deliberou sobre a flexibiliza\u00e7\u00e3o e relaxamento das atividades econ\u00f4micas e n\u00e3o econ\u00f4micas no \u00e2mbito do munic\u00edpio de Goi\u00e2nia.<\/p>\n\n\n\n<p>O documento menciona, ainda, que a Secretaria Estadual de Educa\u00e7\u00e3o do Estado de Goi\u00e1s emitiu a Nota T\u00e9cnica n\u00ba 15\/2020 \u2013 GAB 03076, em que regulamenta a retomada das aulas presenciais nas institui\u00e7\u00f5es de ensino do Estado de Goi\u00e1s, em todos os n\u00edveis educacionais.<\/p>\n\n\n\n<p>Para o retorno \u00e0s atividades presenciais em todos os n\u00edveis, as institui\u00e7\u00f5es de ensino, p\u00fablicas e privadas, dever\u00e3o obedecer rigorosamente aos protocolos sanit\u00e1rios estabelecidos em Nota T\u00e9cnica da Secret\u00e1ria Municipal de Sa\u00fade ou outros por ela adotados, ressaltando que se trata de uma autoriza\u00e7\u00e3o para as institui\u00e7\u00f5es que tiverem a inten\u00e7\u00e3o de retornar, n\u00e3o uma obrigatoriedade.<\/p>\n\n\n\n<p><a href=\"https:\/\/setasistemas.com.br\/blog\/setasistemas-anexos\/decreto-1-968224-prefeituradegoiania-voltaasaulas.pdf\">Veja o decreto aqui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decreto assinado pelo prefeito Iris Rezende e publicado no Di\u00e1rio Oficial do Munic\u00edpio nesta quarta-feira (11\/11) autorizou a retomada das aulas presenciais em todos os n\u00edveis das institui\u00e7\u00f5es de ensino p\u00fablicas e privadas em Goi\u00e2nia. As aulas presenciais estavam suspensas na capital desde mar\u00e7o \u00faltimo, quando a cidade foi alcan\u00e7ada pela pandemia do novo coronav\u00edrus. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[232,92,116,233],"class_list":["post-803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-aulaspresenciais","tag-homeoffice","tag-pandemia-teletrabalho","tag-retomada-das-aulaspresenciais"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=803"}],"version-history":[{"count":1,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/803\/revisions"}],"predecessor-version":[{"id":805,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/803\/revisions\/805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/media\/1378"}],"wp:attachment":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}