{"id":68,"date":"2014-07-29T14:15:59","date_gmt":"2014-07-29T17:15:59","guid":{"rendered":"https:\/\/www.setasistemas.com.br\/blog\/?p=68"},"modified":"2022-11-07T09:17:08","modified_gmt":"2022-11-07T12:17:08","slug":"educacao-infantil","status":"publish","type":"post","link":"https:\/\/www.setasistemas.com.br\/blog\/2014\/07\/29\/educacao-infantil\/","title":{"rendered":"Educa\u00e7\u00e3o Infantil"},"content":{"rendered":"\n<p>A educa\u00e7\u00e3o infantil \u00e9 a primeira etapa da educa\u00e7\u00e3o b\u00e1sica. \u00c9 a \u00fanica que est\u00e1 vinculada a uma idade pr\u00f3pria: atende crian\u00e7as de zero a tr\u00eas anos na creche e de quatro e cinco anos na pr\u00e9-escola. Tem como finalidade o desenvolvimento integral da crian\u00e7a em seus aspectos f\u00edsico, psicol\u00f3gico, intelectual e social, complementando a a\u00e7\u00e3o da fam\u00edlia e da comunidade (LDB, art.29).<\/p>\n\n\n\n<p>Esse tratamento integral das v\u00e1rias dimens\u00f5es do desenvolvimento infantil exige a indissociabilidade do educar e do cuidar no atendimento \u00e0s crian\u00e7as. A educa\u00e7\u00e3o infantil, como dever do Estado, \u00e9 ofertada em institui\u00e7\u00f5es pr\u00f3prias \u2014 creches para crian\u00e7as at\u00e9 tr\u00eas anos e pr\u00e9-escolas para crian\u00e7as de quatro e cinco anos \u2014 em jornada diurna de tempo parcial ou integral, por meio de pr\u00e1ticas pedag\u00f3gicas cotidianas. Essas pr\u00e1ticas devem ser intencionalmente planejadas, sistematizadas e avaliadas em um projeto pol\u00edtico-pedag\u00f3gico que deve ser elaborado coletiva e democraticamente com a participa\u00e7\u00e3o da comunidade escolar e desenvolvido por professores habilitados. A educa\u00e7\u00e3o infantil, cuja matr\u00edcula na pr\u00e9-escola \u00e9 obrigat\u00f3ria para crian\u00e7as de quatro e cinco anos, deve ocorrer em espa\u00e7os institucionais, coletivos, n\u00e3o dom\u00e9sticos, p\u00fablicos ou privados, caracterizados como estabelecimentos educacionais e submetidos a m\u00faltiplos mecanismos de acompanhamento e controle social.<\/p>\n\n\n\n<p>A partir da significativa demanda e expans\u00e3o da educa\u00e7\u00e3o infantil, e considerando as compet\u00eancias da Uni\u00e3o de coordenar a Pol\u00edtica Nacional de Educa\u00e7\u00e3o, de prestar assist\u00eancia t\u00e9cnica e financeira aos Estados, ao Distrito Federal e aos Munic\u00edpios para o desenvolvimento da educa\u00e7\u00e3o e de estabelecer diretrizes para a educa\u00e7\u00e3o infantil, o Minist\u00e9rio da Educa\u00e7\u00e3o vem implementando a\u00e7\u00f5es com vistas a garantir n\u00e3o apenas a expans\u00e3o da oferta de educa\u00e7\u00e3o infantil, mas tamb\u00e9m a qualidade no atendimento \u00e0s crian\u00e7as de zero a seis anos de idade, em creches e pr\u00e9-escolas.<\/p>\n\n\n\n<p>A educa\u00e7\u00e3o infantil \u00e9 um direito humano e social de todas as crian\u00e7as at\u00e9 seis anos de idade, sem distin\u00e7\u00e3o decorrente de origem geogr\u00e1fica, caracteres do fen\u00f3tipo (cor da pele, tra\u00e7os de rosto e cabelo), da etnia, nacionalidade, sexo, de defici\u00eancia f\u00edsica ou mental, n\u00edvel socioecon\u00f4mico ou classe social. Tamb\u00e9m n\u00e3o est\u00e1 atrelada \u00e0 situa\u00e7\u00e3o trabalhista dos pais nem ao n\u00edvel de instru\u00e7\u00e3o, religi\u00e3o, opini\u00e3o pol\u00edtica ou orienta\u00e7\u00e3o sexual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A educa\u00e7\u00e3o infantil \u00e9 a primeira etapa da educa\u00e7\u00e3o b\u00e1sica. \u00c9 a \u00fanica que est\u00e1 vinculada a uma idade pr\u00f3pria: atende crian\u00e7as de zero a tr\u00eas anos na creche e de quatro e cinco anos na pr\u00e9-escola. Tem como finalidade o desenvolvimento integral da crian\u00e7a em seus aspectos f\u00edsico, psicol\u00f3gico, intelectual e social, complementando a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11,24,23],"tags":[],"class_list":["post-68","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-educacao-infantil","category-escola","category-gestao-escolar"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":1,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/68\/revisions"}],"predecessor-version":[{"id":69,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/68\/revisions\/69"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/media\/1401"}],"wp:attachment":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=68"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=68"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}