{"id":1598,"date":"2024-05-13T09:30:00","date_gmt":"2024-05-13T12:30:00","guid":{"rendered":"https:\/\/www.setasistemas.com.br\/blog\/?p=1598"},"modified":"2025-01-20T15:02:55","modified_gmt":"2025-01-20T18:02:55","slug":"a-vanguarda-do-atraso-professores-fazem-mobilizacao-contra-uso-de-plataformas-digitais-em-sp","status":"publish","type":"post","link":"https:\/\/www.setasistemas.com.br\/blog\/2024\/05\/13\/a-vanguarda-do-atraso-professores-fazem-mobilizacao-contra-uso-de-plataformas-digitais-em-sp\/","title":{"rendered":"A vanguarda do atraso: Professores fazem mobiliza\u00e7\u00e3o contra uso de plataformas digitais em SP"},"content":{"rendered":"\n<p>Os professores da rede p\u00fablica estadual de S\u00e3o Paulo articularam uma mobiliza\u00e7\u00e3o contra as plataformas digitais nas escolas. No ano passado, o governo estadual implementou um sistema de ensino baseado em aplicativos, com conte\u00fado e atividades pr\u00e9-estabelecidas.<\/p>\n\n\n\n<p>O Sindicato dos Professores do Ensino Oficial do Estado de S\u00e3o Paulo (Apeoesp) afirma que o m\u00e9todo tira autonomia dos professores e convocou os profissionais a n\u00e3o usarem as plataformas ao longo da pr\u00f3xima semana. O sistema, no entanto, registra se o material foi usado ou n\u00e3o em sala de aula. Os acessos \u00e0 plataforma se tornaram um dos fatores medidos para avaliar escolas e profissionais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Falta de autonomia<\/h2>\n\n\n\n<p>\u201cVoc\u00ea n\u00e3o pode padronizar uma rede do tamanho do estado de S\u00e3o Paulo, com a diversidade e com a especificidade que cada escola, cada regi\u00e3o tem. O aplicativo faz isso. E o professor, se ele n\u00e3o estiver seguindo o aplicativo, o pr\u00f3prio sistema j\u00e1 comunica \u00e0 dire\u00e7\u00e3o da escola e o diretor \u00e9 obrigado a ir at\u00e9 a sala de aula, chamar a aten\u00e7\u00e3o do professor\u201d, critica o presidente da Apeoesp, F\u00e1bio Moraes.<\/p>\n\n\n\n<p>O m\u00e9todo, segundo ele, provocou praticamente o abandono dos livros did\u00e1ticos e impede que o professor busque formas diferentes de abordar os conte\u00fados em sala de aula. \u201cN\u00f3s queremos tecnologia, escolas estruturadas, profissionais valorizados e n\u00f3s queremos resguardar a nossa liberdade de c\u00e1tedra. Se eu achar que a plataforma \u00e9 melhor, eu uso a plataforma. Se eu achar que aquele assunto, o livro, aborda melhor, eu uso o livro. Se eu quiser, eu elaboro o meu material com os meus alunos. Quantas vezes n\u00e3o fizemos isso? Ent\u00e3o hoje, esse direito do professor est\u00e1 sendo ceifado\u201d, acrescenta o sindicalista.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Material com erros<\/h2>\n\n\n\n<p>Em 2023, o governo de S\u00e3o Paulo chegou a anunciar que iria deixar de participar do Programa Nacional de Livros Did\u00e1ticos (PNLD) do Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), que fornece gratuitamente livros para serem usados pelas redes de ensino. A Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo afirmou \u00e0 \u00e9poca que n\u00e3o usaria livros f\u00edsicos em sala de aula e que os alunos teriam apenas material digital.<\/p>\n\n\n\n<p>Ap\u00f3s a repercuss\u00e3o negativa e uma decis\u00e3o judicial contr\u00e1ria \u00e0 sa\u00edda da rede estadual do PNLD, o governo informou que continuaria a receber os livros do programa nacional. Na ocasi\u00e3o, tamb\u00e9m foram identificados erros grosseiros de informa\u00e7\u00e3o no material elaborado pela secretaria estadual.<\/p>\n\n\n\n<p>Em um dos trechos, era dito que, em 1888, Dom Pedro II assinou a Lei \u00c1urea, quando, na verdade, a lei que encerrou a escravid\u00e3o institucionalizada no Brasil foi assinada pela filha do monarca, a Princesa Isabel. Em outro trecho se afirmava, tamb\u00e9m de forma equivocada, que o transtorno do d\u00e9ficit de aten\u00e7\u00e3o e hiperatividade \u00e9 transmiss\u00edvel pela \u00e1gua.<\/p>\n\n\n\n<p>Moraes diz que a falta de qualidade continua sendo uma cr\u00edtica ao material did\u00e1tico que tem sido oferecido pela secretaria de educa\u00e7\u00e3o. \u201cN\u00f3s temos material melhor. N\u00f3s podemos criar material melhor. N\u00f3s temos livros did\u00e1ticos melhores que a rede\u201d, diz.<\/p>\n\n\n\n<p>Neste ano, o governo de S\u00e3o Paulo anunciou que vai usar ferramentas de intelig\u00eancia artificial para elabora\u00e7\u00e3o do material did\u00e1tico para a rede estadual. \u201cAs aulas que j\u00e1 foram produzidas por um professor curriculista, e j\u00e1 est\u00e3o em uso na rede, s\u00e3o aprimoradas pela IA [intelig\u00eancia artificial] com a inser\u00e7\u00e3o de novas propostas de atividades, exemplos de aplica\u00e7\u00e3o pr\u00e1tica do conhecimento e informa\u00e7\u00f5es adicionais que enrique\u00e7am as explica\u00e7\u00f5es de conceitos-chave de cada aula\u201d, afirmou a secretaria de educa\u00e7\u00e3o em abril.<\/p>\n\n\n\n<p>Em nota enviada, a Secretaria Estadual de Educa\u00e7\u00e3o de S\u00e3o Paulo diz que &#8220;as plataformas digitais s\u00e3o recursos tecnol\u00f3gicos agregadores na produ\u00e7\u00e3o pedag\u00f3gica desenvolvida em sala de aula, fazendo parte do conte\u00fado ministrado pelos docentes, e continuam sendo utilizadas normalmente&#8221;.<\/p>\n\n\n\n<p>Ainda segundo a pasta, &#8220;todos os recursos oferecidos pela a Secretaria da Educa\u00e7\u00e3o t\u00eam o objetivo de aprimorar as habilidades dos estudantes e promover o avan\u00e7o dos \u00edndices educacionais de S\u00e3o Paulo&#8221;.&nbsp;<\/p>\n\n\n\n<p><em>*Mat\u00e9ria ampliada \u00e0s 17h06&nbsp;do dia 13 de maio para inclus\u00e3o de posicionamento da Secretaria de Educa\u00e7\u00e3o.&nbsp;<\/em><\/p>\n\n\n\n<p>Fonte: EBC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os professores da rede p\u00fablica estadual de S\u00e3o Paulo articularam uma mobiliza\u00e7\u00e3o contra as plataformas digitais nas escolas. No ano passado, o governo estadual implementou um sistema de ensino baseado em aplicativos, com conte\u00fado e atividades pr\u00e9-estabelecidas.<\/p>\n","protected":false},"author":1,"featured_media":1335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,24,178,21,23],"tags":[397,396,395],"class_list":["post-1598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-escola","category-escolar","category-formacao","category-gestao-escolar","tag-pnld","tag-professores-acomodados","tag-retrocesso-na-educacao"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/1598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1598"}],"version-history":[{"count":3,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/1598\/revisions"}],"predecessor-version":[{"id":1685,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/1598\/revisions\/1685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/media\/1335"}],"wp:attachment":[{"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.setasistemas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}